{"id":443,"date":"2023-02-02T15:10:46","date_gmt":"2023-02-02T14:10:46","guid":{"rendered":"http:\/\/www.krantz.unipr.it\/?post_type=product&#038;p=443"},"modified":"2023-02-02T15:16:02","modified_gmt":"2023-02-02T14:16:02","slug":"143-marna","status":"publish","type":"product","link":"http:\/\/www.krantz.unipr.it\/index.php\/prodotto\/143-marna\/","title":{"rendered":"143-Marna"},"content":{"rendered":"<p><strong>VISTA A 360\u00b0<\/strong><br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.krantz.unipr.it\/360\/143-Marna\/143-Marna.html\" width=\"1100\" height=\"700\"><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\"><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span>\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Collocazione: <\/strong>Vetrina 11, quarto ripiano<\/p>\n<p><strong>Localit\u00e0: <\/strong>Thale (Harz) &#8211; Germania<\/p>\n<p><b><span data-contrast=\"auto\">Descrizione macroscopica:<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p>La marna \u00e8 una roccia sedimentaria, di tipo terrigeno, composta da una frazione argillosa e da una frazione carbonatica data generalmente da carbonato di calcio (calcite) CaCO3, oppure da carbonato doppio di magnesio e calcio (dolomite) [MgCa(CO3)2]. Nelle marne tipiche la percentuale di carbonato di calcio va dal 35% al 65%; al di sopra e al di sotto di questi valori si hanno termini transizionali a calcari (o dolomie) per alti contenuti di carbonato, oppure ad argille per bassi contenuti di carbonato. Questo tipo di roccia deriva da sedimenti fangosi, di origine prevalentemente marina, sedimentati in condizioni di bassa energia del mezzo.<br \/>\nLa componente argillosa si depone per lenta decantazione di particelle d&#8217;argilla (dimensioni inferiori a 0,0625 mm).<br \/>\nLa componente carbonatica pu\u00f2 essere originata dalla precipitazione di sali o dalla deposizione di particelle organogene, derivate cio\u00e8 da resti microscopici di organismi a scheletro o guscio calcareo.<br \/>\nL&#8217;utilizzo industriale principale delle marne \u00e8 nella produzione di miscele cementizie.(Wikipedia)<\/p>\n<p><b><span data-contrast=\"auto\">Descrizione\u00a0<\/span><\/b><b><span data-contrast=\"auto\">microfoto<\/span><\/b><b><span data-contrast=\"auto\">:<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><strong>prima immagine:\u00a0<\/strong><\/p>\n<p><strong>seconda immagine:<\/strong><\/p>\n<p><strong>terza immagine:\u00a0<\/strong><\/p>\n","protected":false},"featured_media":444,"template":"","meta":{"_lmt_disableupdate":"","_lmt_disable":""},"product_cat":[20],"product_tag":[],"class_list":{"0":"post-443","1":"product","2":"type-product","3":"status-publish","6":"product_cat-sedimentarie","8":"first","9":"outofstock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/product\/443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/media\/444"}],"wp:attachment":[{"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/media?parent=443"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/product_cat?post=443"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/product_tag?post=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}