{"id":107,"date":"2022-11-04T08:19:28","date_gmt":"2022-11-04T07:19:28","guid":{"rendered":"http:\/\/www.krantz.unipr.it\/?post_type=product&#038;p=107"},"modified":"2022-11-04T08:25:13","modified_gmt":"2022-11-04T07:25:13","slug":"004-farina-fossile","status":"publish","type":"product","link":"http:\/\/www.krantz.unipr.it\/index.php\/prodotto\/004-farina-fossile\/","title":{"rendered":"004-Farina fossile"},"content":{"rendered":"<p><strong>VISTA A 360\u00b0<\/strong><br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.krantz.unipr.it\/360\/004-Farina fossile\/004-Farina fossile.html\" width=\"1100\" height=\"700\"><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Collocazione: <\/strong>Vetrina 11, primo ripiano<\/p>\n<p><strong>Localit\u00e0:\u00a0<\/strong>Bruex Boemia (Rep. Ceca)<\/p>\n<p><b><span data-contrast=\"auto\">Descrizione macroscopica:<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p>La farina fossile (o sabbia di diatomee o terra diatomacea o diatomite o kieselgur) \u00e8 una roccia silicea sedimentaria di origine organica ed \u00e8 il residuo fossile di microscopiche alghe della famiglia delle diatomee.<\/p>\n<p>Si forma in ambiente lacustre o marino, dalla sedimentazione sul fondo dei gusci silicei delle diatomee, a cui in ambiente marino possono essere pi\u00f9 o meno mescolati quelli dei foraminiferi (calcarei). A seconda dell&#8217;ambiente di deposizione, si possono ottenere la farina fossile (formatasi in ambiente lacustre, solo dalle diatomee) o i tripoli (ambiente marino, dalle diatomee e dai foraminiferi).<\/p>\n<p>La composizione chimica vede una elevata percentuale di carbonato di calcio e diossido di silicio, dipendentemente dalla collocazione geografica e della storia geologica del suddetto residuo. (fonte wikipedia)<\/p>\n<p><b><span data-contrast=\"auto\">Descrizione\u00a0<\/span><\/b><b><span data-contrast=\"auto\">microfoto<\/span><\/b><b><span data-contrast=\"auto\">:<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p>In allestimento<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":108,"template":"","meta":{"_lmt_disableupdate":"","_lmt_disable":""},"product_cat":[20],"product_tag":[],"class_list":{"0":"post-107","1":"product","2":"type-product","3":"status-publish","6":"product_cat-sedimentarie","8":"first","9":"outofstock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/product\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/media\/108"}],"wp:attachment":[{"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/media?parent=107"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/product_cat?post=107"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/www.krantz.unipr.it\/index.php\/wp-json\/wp\/v2\/product_tag?post=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}